{"id":508,"date":"2019-06-27T17:48:02","date_gmt":"2019-06-27T15:48:02","guid":{"rendered":"http:\/\/demo.netech.it\/duea\/?post_type=prodotti&#038;p=508"},"modified":"2024-05-30T17:17:25","modified_gmt":"2024-05-30T15:17:25","slug":"box-post-svezzamento","status":"publish","type":"prodotti","link":"https:\/\/www.antoniniduea.it\/it\/prodotti\/box-post-svezzamento\/","title":{"rendered":"Box post-svezzamento"},"content":{"rendered":"\r\n<p>Box post svezzamento per vitelli fino a circa 6 mesi di vita, utilizzato all\u2019esterno della stalla, facilmente spostabile, pu\u00f2 contenere fino a 12 vitelli. Coibentato nelle pareti e nel tetto, pu\u00f2 essere accessoriato con autocatture, mangiatoia e abbeveratoio in base alla tipologia di animale, apribile anteriormente per facilitare la pulizia.<\/p>\r\n\r\n\r\n\r\n<p>&nbsp;<\/p>\r\n<div class=\"schedetecniche\"><button class=\"accordion\">Scarica la Scheda Tecnica<\/button>\r\n<div class=\"panel\"><div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f5741-o1\" lang=\"it-IT\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/prodotti\/508#wpcf7-f5741-o1\" method=\"post\" class=\"wpcf7-form init adv-dem-ext-1.1.0\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"5741\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.4\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5741-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<p><label> Nome e Cognome*<br \/>\n    <span class=\"wpcf7-form-control-wrap your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome e Cognome\" \/><\/span> <\/label><\/p>\n<p><label> Email*<br \/>\n    <span class=\"wpcf7-form-control-wrap your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" \/><\/span> <\/label><\/p>\n<p><label> CAP*<br \/>\n     <span class=\"wpcf7-form-control-wrap CAP\"><input type=\"text\" name=\"CAP\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"CAP\" \/><\/span><\/label><br \/>\n<label> Comune*<br \/>\n     <span class=\"wpcf7-form-control-wrap Comune\"><input type=\"text\" name=\"Comune\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Comune\" \/><\/span><\/label><br \/>\n<label> Provincia*<br \/>\n     <span class=\"wpcf7-form-control-wrap Provincia\"><input type=\"text\" name=\"Provincia\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Provincia\" \/><\/span><\/label><\/p>\n<p><label> Telefono*<br \/>\n     <span class=\"wpcf7-form-control-wrap Telefono\"><input type=\"tel\" name=\"Telefono\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Telefono\" \/><\/span><\/label><\/p>\n<p><label> Privacy Policy*<br \/>\n<span class=\"wpcf7-form-control-wrap PrivacyPolicy\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"PrivacyPolicy\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Ho letto e accetto i termini della informativa sulla <a href='https:\/\/www.antoniniduea.it\/it\/privacy-policy-cookies\/' target='_blank'>privacy<\/a> e acconsento il trattamento dei dati<\/span><\/label><\/span><\/span><\/span><\/label><\/p>\n<p><label> Marketing<br \/>\n<span class=\"wpcf7-form-control-wrap newsletter\"><span class=\"wpcf7-form-control wpcf7-acceptance optional\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"newsletter\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Desidero ricevere informazioni sui prodotti e offerte da questo sito<\/span><\/label><\/span><\/span><\/span><\/label><\/p>\n<p><input type=\"submit\" value=\"Scarica\" class=\"wpcf7-form-control wpcf7-submit\" \/><\/p>\n<p style=\"display: none !important;\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"192\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><p style=\"display: none !important\"><span class=\"wpcf7-form-control-wrap referer-page\"><input type=\"hidden\" name=\"referer-page\" value=\"direct visit\" size=\"40\" class=\"wpcf7-form-control wpcf7-text referer-page\" aria-invalid=\"false\"><\/span><\/p>\n<!-- 4Dem extension --><\/form><\/div><\/div>\r\n<\/div>\r\n\r\n<p>&nbsp;<\/p>","protected":false},"featured_media":1296,"template":"","categoria_prodotto":[18],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.9.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Box post svezzamento | Sfoglia tutti i prodotti DueA<\/title>\n<meta name=\"description\" content=\"Box post svezzamento per vitelli fino a circa 6 mesi di vita, utilizzato all\u2019esterno della stalla, facilmente spostabile, contiene fino a 12 vitelli.\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.antoniniduea.it\/it\/prodotti\/box-post-svezzamento\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Box post svezzamento | Sfoglia tutti i prodotti DueA\" \/>\n<meta property=\"og:description\" content=\"Box post svezzamento per vitelli fino a circa 6 mesi di vita, utilizzato all\u2019esterno della stalla, facilmente spostabile, contiene fino a 12 vitelli.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.antoniniduea.it\/it\/prodotti\/box-post-svezzamento\/\" \/>\n<meta property=\"og:site_name\" content=\"DUE A\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-30T15:17:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.antoniniduea.it\/wp-content\/uploads\/2019\/06\/box-post-svezzamento.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\">\n\t<meta name=\"twitter:data1\" content=\"1 minuto\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.antoniniduea.it\/it\/#organization\",\"name\":\"Antonini DueA\",\"url\":\"https:\/\/www.antoniniduea.it\/it\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.antoniniduea.it\/it\/#logo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.antoniniduea.it\/wp-content\/uploads\/2021\/03\/logo-duea-agrizootech.png\",\"width\":187,\"height\":100,\"caption\":\"Antonini DueA\"},\"image\":{\"@id\":\"https:\/\/www.antoniniduea.it\/it\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.antoniniduea.it\/it\/#website\",\"url\":\"https:\/\/www.antoniniduea.it\/it\/\",\"name\":\"DUE A\",\"description\":\"Produzione Tunnel Agricoli, Box per vitelli nuovi e usati\",\"publisher\":{\"@id\":\"https:\/\/www.antoniniduea.it\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.antoniniduea.it\/it\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.antoniniduea.it\/it\/prodotti\/box-post-svezzamento\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.antoniniduea.it\/wp-content\/uploads\/2019\/06\/box-post-svezzamento.jpg\",\"width\":480,\"height\":480},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.antoniniduea.it\/it\/prodotti\/box-post-svezzamento\/#webpage\",\"url\":\"https:\/\/www.antoniniduea.it\/it\/prodotti\/box-post-svezzamento\/\",\"name\":\"Box post svezzamento | Sfoglia tutti i prodotti DueA\",\"isPartOf\":{\"@id\":\"https:\/\/www.antoniniduea.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.antoniniduea.it\/it\/prodotti\/box-post-svezzamento\/#primaryimage\"},\"datePublished\":\"2019-06-27T15:48:02+00:00\",\"dateModified\":\"2024-05-30T15:17:25+00:00\",\"description\":\"Box post svezzamento per vitelli fino a circa 6 mesi di vita, utilizzato all\\u2019esterno della stalla, facilmente spostabile, contiene fino a 12 vitelli.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.antoniniduea.it\/it\/prodotti\/box-post-svezzamento\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.antoniniduea.it\/it\/prodotti\/box-post-svezzamento\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.antoniniduea.it\/it\/prodotti\/box-post-svezzamento\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.antoniniduea.it\/it\/\",\"url\":\"https:\/\/www.antoniniduea.it\/it\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.antoniniduea.it\/it\/prodotti\/box-post-svezzamento\/\",\"url\":\"https:\/\/www.antoniniduea.it\/it\/prodotti\/box-post-svezzamento\/\",\"name\":\"Box post-svezzamento\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.antoniniduea.it\/it\/wp-json\/wp\/v2\/prodotti\/508"}],"collection":[{"href":"https:\/\/www.antoniniduea.it\/it\/wp-json\/wp\/v2\/prodotti"}],"about":[{"href":"https:\/\/www.antoniniduea.it\/it\/wp-json\/wp\/v2\/types\/prodotti"}],"version-history":[{"count":4,"href":"https:\/\/www.antoniniduea.it\/it\/wp-json\/wp\/v2\/prodotti\/508\/revisions"}],"predecessor-version":[{"id":9886,"href":"https:\/\/www.antoniniduea.it\/it\/wp-json\/wp\/v2\/prodotti\/508\/revisions\/9886"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.antoniniduea.it\/it\/wp-json\/wp\/v2\/media\/1296"}],"wp:attachment":[{"href":"https:\/\/www.antoniniduea.it\/it\/wp-json\/wp\/v2\/media?parent=508"}],"wp:term":[{"taxonomy":"categoria_prodotto","embeddable":true,"href":"https:\/\/www.antoniniduea.it\/it\/wp-json\/wp\/v2\/categoria_prodotto?post=508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}